{"id":2918,"date":"2023-12-26T12:21:58","date_gmt":"2023-12-26T12:21:58","guid":{"rendered":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343.jpg"},"modified":"2023-12-26T16:20:56","modified_gmt":"2023-12-26T16:20:56","slug":"img_3343-2","status":"inherit","type":"attachment","link":"http:\/\/www.itziararetxaga.net\/eu\/2023\/12\/hego-afrikako-44-isya\/img_3343-2\/","title":{"rendered":"IMG_3343"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-2918","attachment","type-attachment","status-inherit","czr-hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-200x300.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-200x300.jpg 200w, http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-683x1024.jpg 683w, http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-768x1152.jpg 768w, http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-1024x1536.jpg 1024w, http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-1365x2048.jpg 1365w, http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-570x855.jpg 570w, http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-scaled.jpg 1707w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>&#8220;The Thorn Picker&#8221; by <\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1707,"height":2560,"file":"2023\/12\/IMG_3343-scaled.jpg","filesize":856258,"sizes":{"medium":{"file":"IMG_3343-200x300.jpg","width":200,"height":300,"filesize":45394,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-200x300.jpg"},"large":{"file":"IMG_3343-683x1024.jpg","width":683,"height":1024,"filesize":171454,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-683x1024.jpg"},"thumbnail":{"file":"IMG_3343-150x150.jpg","width":150,"height":150,"filesize":38985,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-150x150.jpg"},"medium_large":{"file":"IMG_3343-768x1152.jpg","width":768,"height":1152,"filesize":206625,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-768x1152.jpg"},"1536x1536":{"file":"IMG_3343-1024x1536.jpg","width":1024,"height":1536,"filesize":342088,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-1024x1536.jpg"},"2048x2048":{"file":"IMG_3343-1365x2048.jpg","width":1365,"height":2048,"filesize":574323,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-1365x2048.jpg"},"tc-masonry-thumb-size":{"file":"IMG_3343-570x855.jpg","width":570,"height":855,"filesize":129341,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-570x855.jpg"},"tc-masonry-bi-thumb-size":{"file":"IMG_3343-570x869.jpg","width":570,"height":869,"filesize":131175,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-570x869.jpg"},"tc-grid-full":{"file":"IMG_3343-1110x444.jpg","width":1110,"height":444,"filesize":177469,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-1110x444.jpg"},"tc-grid":{"file":"IMG_3343-570x350.jpg","width":570,"height":350,"filesize":85472,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-570x350.jpg"},"tc-thumb":{"file":"IMG_3343-270x250.jpg","width":270,"height":250,"filesize":49291,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-270x250.jpg"},"slider":{"file":"IMG_3343-1110x500.jpg","width":1110,"height":500,"filesize":190442,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-1110x500.jpg"},"tc-sq-thumb":{"file":"IMG_3343-510x510.jpg","width":510,"height":510,"filesize":89965,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-510x510.jpg"},"tc-ws-thumb":{"file":"IMG_3343-1110x624.jpg","width":1110,"height":624,"filesize":217772,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-1110x624.jpg"},"tc-ws-small-thumb":{"file":"IMG_3343-528x297.jpg","width":528,"height":297,"filesize":75334,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-528x297.jpg"},"tc-slider-small":{"file":"IMG_3343-517x235.jpg","width":517,"height":235,"filesize":68001,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-517x235.jpg"},"fpc-size":{"file":"IMG_3343-270x250.jpg","width":270,"height":250,"filesize":49291,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-270x250.jpg"},"full":{"file":"IMG_3343-scaled.jpg","width":1707,"height":2560,"mime_type":"image\/jpeg","source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-scaled.jpg"}},"image_meta":{"aperture":"5","credit":"","camera":"Canon PowerShot G7 X Mark II","caption":"","created_timestamp":"1702190106","copyright":"","focal_length":"8.8","iso":"125","shutter_speed":"0.0008","title":"","orientation":1,"keywords":[]},"original_image":"IMG_3343.jpg"},"post":2926,"source_url":"http:\/\/www.itziararetxaga.net\/wp-content\/uploads\/2023\/12\/IMG_3343-scaled.jpg","_links":{"self":[{"href":"http:\/\/www.itziararetxaga.net\/eu\/wp-json\/wp\/v2\/media\/2918"}],"collection":[{"href":"http:\/\/www.itziararetxaga.net\/eu\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.itziararetxaga.net\/eu\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.itziararetxaga.net\/eu\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.itziararetxaga.net\/eu\/wp-json\/wp\/v2\/comments?post=2918"}]}}